{"id":245,"date":"2023-04-24T16:44:55","date_gmt":"2023-04-24T19:44:55","guid":{"rendered":"http:\/\/pizzornowines.com\/?post_type=product&#038;p=13922"},"modified":"2025-06-29T12:01:53","modified_gmt":"2025-06-29T15:01:53","slug":"especiales-10m-reserva-sauvignon-blanc","status":"publish","type":"product","link":"https:\/\/pizzornowines.com\/pt\/produto\/especiales-10m-reserva-sauvignon-blanc\/","title":{"rendered":"10.000 M &#8211; Reserva Sauvginon Blanc"},"content":{"rendered":"<p>Vino elaborado a partir de uvas en perfecto estado de madurez, provenientes de parcelas seleccionadas con podas en verde. Al momento de la cosecha solo los racimos de m\u00e1xima calidad van a ser utilizados para formar parte de este reserva. Al ingresar a bodega, los racimos pasan por un riguroso proceso de selecci\u00f3n. Un 30% del jugo es fermentado en barricas de roble franc\u00e9s, con una posterior crianza de 3 meses sobre las l\u00edas. Mientras que el 70% restante en tanques de acero inoxidable.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vino elaborado a partir de uvas en perfecto estado de madurez, provenientes de parcelas seleccionadas con podas en verde. Al momento de la cosecha solo los racimos de m\u00e1xima calidad van a ser utilizados para formar parte de este reserva. Al ingresar a bodega, los racimos pasan por un riguroso proceso de selecci\u00f3n. Un 30% [&hellip;]<\/p>\n","protected":false},"featured_media":246,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"tipo-visita":[],"product_brand":[],"product_cat":[30],"product_tag":[],"class_list":{"0":"post-245","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-10-000-millas","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"exclude_global_add_ons":[],"addons":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10.000 M - Reserva Sauvginon Blanc - Pizzorno Family Estates<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10.000 M - Reserva Sauvginon Blanc - Pizzorno Family Estates\" \/>\n<meta property=\"og:description\" content=\"Vino elaborado a partir de uvas en perfecto estado de madurez, provenientes de parcelas seleccionadas con podas en verde. Al momento de la cosecha solo los racimos de m\u00e1xima calidad van a ser utilizados para formar parte de este reserva. Al ingresar a bodega, los racimos pasan por un riguroso proceso de selecci\u00f3n. Un 30% [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pizzornowines.com\/pt\/produto\/especiales-10m-reserva-sauvignon-blanc\/\" \/>\n<meta property=\"og:site_name\" content=\"Pizzorno Family Estates\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pizzorno.family.estates\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-29T15:01:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pizzornowines.com\/wp-content\/uploads\/2023\/07\/SB.10.000.Reserva.png\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"789\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/especiales-10m-reserva-sauvignon-blanc\\\/\",\"url\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/especiales-10m-reserva-sauvignon-blanc\\\/\",\"name\":\"10.000 M - Reserva Sauvginon Blanc - Pizzorno Family Estates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/especiales-10m-reserva-sauvignon-blanc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/especiales-10m-reserva-sauvignon-blanc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pizzornowines.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/SB.10.000.Reserva.png\",\"datePublished\":\"2023-04-24T19:44:55+00:00\",\"dateModified\":\"2025-06-29T15:01:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/especiales-10m-reserva-sauvignon-blanc\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pizzornowines.com\\\/product\\\/especiales-10m-reserva-sauvignon-blanc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/especiales-10m-reserva-sauvignon-blanc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pizzornowines.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/SB.10.000.Reserva.png\",\"contentUrl\":\"https:\\\/\\\/pizzornowines.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/SB.10.000.Reserva.png\",\"width\":250,\"height\":789},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/especiales-10m-reserva-sauvignon-blanc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pizzornowines.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/pizzornowines.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"10.000 M &#8211; Reserva Sauvginon Blanc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#website\",\"url\":\"https:\\\/\\\/pizzornowines.com\\\/\",\"name\":\"Pizzorno Family Estates\",\"description\":\"Pasi\u00f3n por la tierra y el vino\",\"publisher\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pizzornowines.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#organization\",\"name\":\"Pizzorno Family Estates\",\"url\":\"https:\\\/\\\/pizzornowines.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pizzornowines.com\\\/wp-content\\\/uploads\\\/Pizzorno-Family-Estate-logo.svg\",\"contentUrl\":\"https:\\\/\\\/pizzornowines.com\\\/wp-content\\\/uploads\\\/Pizzorno-Family-Estate-logo.svg\",\"width\":422,\"height\":283,\"caption\":\"Pizzorno Family Estates\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pizzorno.family.estates\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10.000 M - Reserva Sauvginon Blanc - Pizzorno Family Estates","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"10.000 M - Reserva Sauvginon Blanc - Pizzorno Family Estates","og_description":"Vino elaborado a partir de uvas en perfecto estado de madurez, provenientes de parcelas seleccionadas con podas en verde. Al momento de la cosecha solo los racimos de m\u00e1xima calidad van a ser utilizados para formar parte de este reserva. Al ingresar a bodega, los racimos pasan por un riguroso proceso de selecci\u00f3n. Un 30% [&hellip;]","og_url":"https:\/\/pizzornowines.com\/pt\/produto\/especiales-10m-reserva-sauvignon-blanc\/","og_site_name":"Pizzorno Family Estates","article_publisher":"https:\/\/www.facebook.com\/pizzorno.family.estates","article_modified_time":"2025-06-29T15:01:53+00:00","og_image":[{"width":250,"height":789,"url":"https:\/\/pizzornowines.com\/wp-content\/uploads\/2023\/07\/SB.10.000.Reserva.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pizzornowines.com\/product\/especiales-10m-reserva-sauvignon-blanc\/","url":"https:\/\/pizzornowines.com\/product\/especiales-10m-reserva-sauvignon-blanc\/","name":"10.000 M - Reserva Sauvginon Blanc - Pizzorno Family Estates","isPartOf":{"@id":"https:\/\/pizzornowines.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pizzornowines.com\/product\/especiales-10m-reserva-sauvignon-blanc\/#primaryimage"},"image":{"@id":"https:\/\/pizzornowines.com\/product\/especiales-10m-reserva-sauvignon-blanc\/#primaryimage"},"thumbnailUrl":"https:\/\/pizzornowines.com\/wp-content\/uploads\/2023\/07\/SB.10.000.Reserva.png","datePublished":"2023-04-24T19:44:55+00:00","dateModified":"2025-06-29T15:01:53+00:00","breadcrumb":{"@id":"https:\/\/pizzornowines.com\/product\/especiales-10m-reserva-sauvignon-blanc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pizzornowines.com\/product\/especiales-10m-reserva-sauvignon-blanc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/pizzornowines.com\/product\/especiales-10m-reserva-sauvignon-blanc\/#primaryimage","url":"https:\/\/pizzornowines.com\/wp-content\/uploads\/2023\/07\/SB.10.000.Reserva.png","contentUrl":"https:\/\/pizzornowines.com\/wp-content\/uploads\/2023\/07\/SB.10.000.Reserva.png","width":250,"height":789},{"@type":"BreadcrumbList","@id":"https:\/\/pizzornowines.com\/product\/especiales-10m-reserva-sauvignon-blanc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pizzornowines.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/pizzornowines.com\/shop\/"},{"@type":"ListItem","position":3,"name":"10.000 M &#8211; Reserva Sauvginon Blanc"}]},{"@type":"WebSite","@id":"https:\/\/pizzornowines.com\/#website","url":"https:\/\/pizzornowines.com\/","name":"Pizzorno Family Estates","description":"Pasi\u00f3n por la tierra y el vino","publisher":{"@id":"https:\/\/pizzornowines.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pizzornowines.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/pizzornowines.com\/#organization","name":"Pizzorno Family Estates","url":"https:\/\/pizzornowines.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/pizzornowines.com\/#\/schema\/logo\/image\/","url":"https:\/\/pizzornowines.com\/wp-content\/uploads\/Pizzorno-Family-Estate-logo.svg","contentUrl":"https:\/\/pizzornowines.com\/wp-content\/uploads\/Pizzorno-Family-Estate-logo.svg","width":422,"height":283,"caption":"Pizzorno Family Estates"},"image":{"@id":"https:\/\/pizzornowines.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pizzorno.family.estates"]}]}},"_links":{"self":[{"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/product\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/comments?post=245"}],"version-history":[{"count":1,"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/product\/245\/revisions"}],"predecessor-version":[{"id":2726,"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/product\/245\/revisions\/2726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/media\/246"}],"wp:attachment":[{"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/media?parent=245"}],"wp:term":[{"taxonomy":"tipo-visita","embeddable":true,"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/tipo-visita?post=245"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/product_brand?post=245"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/product_cat?post=245"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pizzornowines.com\/pt\/wp-json\/wp\/v2\/product_tag?post=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}