{"id":205,"date":"2024-02-02T11:05:19","date_gmt":"2024-02-02T14:05:19","guid":{"rendered":"http:\/\/pizzornowines.com\/producto\/lobo-suelto\/"},"modified":"2024-02-02T11:05:19","modified_gmt":"2024-02-02T14:05:19","slug":"lobo-suelto","status":"publish","type":"product","link":"https:\/\/pizzornowines.com\/en\/product\/lobo-suelto\/","title":{"rendered":"Lobo Suelto"},"content":{"rendered":"<p>Este Blend de tintas ha sido especialmente dise\u00f1ado para atraer a su futuro objeto de seducci\u00f3n.<br \/>\nSu intenso color rub\u00ed y aromas de frutos rojos maduros dejaran r\u00e1pidamente inmovilizada a su presa. Equilibrado y sincero en boca, sus notas especiadas y final prolongado le dar\u00e1n el marco perfecto para impedir cualquier huida v finalmente, pl\u00e1cidamente, atraerla hacia sus fauces.<br \/>\n* Ideal para utilizarse antes de las comidas como aperitivo, o bien para acompa\u00f1ar pastas y carnes rojas, maridando exitosamente con carnes de cabrito o de cordera.<br \/>\nEn suma, este vino sugestivo y seductor es el arma perfecta para conquistar a su caza, aunque advertimos, con un potencial como para enamorar a una suegra.<\/p>","protected":false},"excerpt":{"rendered":"<p>Este Blend de tintas ha sido especialmente dise\u00f1ado para atraer a su futuro objeto de seducci\u00f3n. Su intenso color rub\u00ed y aromas de frutos rojos maduros dejaran r\u00e1pidamente inmovilizada a su presa. Equilibrado y sincero en boca, sus notas especiadas y final prolongado le dar\u00e1n el marco perfecto para impedir cualquier huida v finalmente, pl\u00e1cidamente, [&hellip;]<\/p>\n","protected":false},"featured_media":206,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"tipo-visita":[],"product_brand":[],"product_cat":[26],"product_tag":[],"class_list":{"0":"post-205","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-especiales","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"exclude_global_add_ons":[],"addons":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lobo Suelto - Pizzorno Family Estates<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lobo Suelto - Pizzorno Family Estates\" \/>\n<meta property=\"og:description\" content=\"Este Blend de tintas ha sido especialmente dise\u00f1ado para atraer a su futuro objeto de seducci\u00f3n. Su intenso color rub\u00ed y aromas de frutos rojos maduros dejaran r\u00e1pidamente inmovilizada a su presa. Equilibrado y sincero en boca, sus notas especiadas y final prolongado le dar\u00e1n el marco perfecto para impedir cualquier huida v finalmente, pl\u00e1cidamente, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pizzornowines.com\/en\/product\/lobo-suelto\/\" \/>\n<meta property=\"og:site_name\" content=\"Pizzorno Family Estates\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pizzorno.family.estates\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pizzornowines.com\/wp-content\/uploads\/2024\/02\/Lobo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/lobo-suelto\\\/\",\"url\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/lobo-suelto\\\/\",\"name\":\"Lobo Suelto - Pizzorno Family Estates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/lobo-suelto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/lobo-suelto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pizzornowines.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Lobo-scaled.jpg\",\"datePublished\":\"2024-02-02T14:05:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/lobo-suelto\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pizzornowines.com\\\/product\\\/lobo-suelto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/lobo-suelto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pizzornowines.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Lobo-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/pizzornowines.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Lobo-scaled.jpg\",\"width\":1250,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/product\\\/lobo-suelto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pizzornowines.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/pizzornowines.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lobo Suelto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#website\",\"url\":\"https:\\\/\\\/pizzornowines.com\\\/\",\"name\":\"Pizzorno Family Estates\",\"description\":\"Pasi\u00f3n por la tierra y el vino\",\"publisher\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pizzornowines.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#organization\",\"name\":\"Pizzorno Family Estates\",\"url\":\"https:\\\/\\\/pizzornowines.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pizzornowines.com\\\/wp-content\\\/uploads\\\/Pizzorno-Family-Estate-logo.svg\",\"contentUrl\":\"https:\\\/\\\/pizzornowines.com\\\/wp-content\\\/uploads\\\/Pizzorno-Family-Estate-logo.svg\",\"width\":422,\"height\":283,\"caption\":\"Pizzorno Family Estates\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzornowines.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pizzorno.family.estates\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lobo Suelto - Pizzorno Family Estates","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Lobo Suelto - Pizzorno Family Estates","og_description":"Este Blend de tintas ha sido especialmente dise\u00f1ado para atraer a su futuro objeto de seducci\u00f3n. Su intenso color rub\u00ed y aromas de frutos rojos maduros dejaran r\u00e1pidamente inmovilizada a su presa. Equilibrado y sincero en boca, sus notas especiadas y final prolongado le dar\u00e1n el marco perfecto para impedir cualquier huida v finalmente, pl\u00e1cidamente, [&hellip;]","og_url":"https:\/\/pizzornowines.com\/en\/product\/lobo-suelto\/","og_site_name":"Pizzorno Family Estates","article_publisher":"https:\/\/www.facebook.com\/pizzorno.family.estates","og_image":[{"width":1250,"height":2560,"url":"https:\/\/pizzornowines.com\/wp-content\/uploads\/2024\/02\/Lobo-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pizzornowines.com\/product\/lobo-suelto\/","url":"https:\/\/pizzornowines.com\/product\/lobo-suelto\/","name":"Lobo Suelto - Pizzorno Family Estates","isPartOf":{"@id":"https:\/\/pizzornowines.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pizzornowines.com\/product\/lobo-suelto\/#primaryimage"},"image":{"@id":"https:\/\/pizzornowines.com\/product\/lobo-suelto\/#primaryimage"},"thumbnailUrl":"https:\/\/pizzornowines.com\/wp-content\/uploads\/2024\/02\/Lobo-scaled.jpg","datePublished":"2024-02-02T14:05:19+00:00","breadcrumb":{"@id":"https:\/\/pizzornowines.com\/product\/lobo-suelto\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pizzornowines.com\/product\/lobo-suelto\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pizzornowines.com\/product\/lobo-suelto\/#primaryimage","url":"https:\/\/pizzornowines.com\/wp-content\/uploads\/2024\/02\/Lobo-scaled.jpg","contentUrl":"https:\/\/pizzornowines.com\/wp-content\/uploads\/2024\/02\/Lobo-scaled.jpg","width":1250,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/pizzornowines.com\/product\/lobo-suelto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pizzornowines.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/pizzornowines.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Lobo Suelto"}]},{"@type":"WebSite","@id":"https:\/\/pizzornowines.com\/#website","url":"https:\/\/pizzornowines.com\/","name":"Pizzorno Family Estates","description":"Pasi\u00f3n por la tierra y el vino","publisher":{"@id":"https:\/\/pizzornowines.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pizzornowines.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pizzornowines.com\/#organization","name":"Pizzorno Family Estates","url":"https:\/\/pizzornowines.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pizzornowines.com\/#\/schema\/logo\/image\/","url":"https:\/\/pizzornowines.com\/wp-content\/uploads\/Pizzorno-Family-Estate-logo.svg","contentUrl":"https:\/\/pizzornowines.com\/wp-content\/uploads\/Pizzorno-Family-Estate-logo.svg","width":422,"height":283,"caption":"Pizzorno Family Estates"},"image":{"@id":"https:\/\/pizzornowines.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pizzorno.family.estates"]}]}},"_links":{"self":[{"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/product\/205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/comments?post=205"}],"version-history":[{"count":0,"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/product\/205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/media\/206"}],"wp:attachment":[{"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/media?parent=205"}],"wp:term":[{"taxonomy":"tipo-visita","embeddable":true,"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/tipo-visita?post=205"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/product_brand?post=205"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/product_cat?post=205"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pizzornowines.com\/en\/wp-json\/wp\/v2\/product_tag?post=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}